{"id":8396,"date":"2026-02-06T15:00:59","date_gmt":"2026-02-06T08:00:59","guid":{"rendered":"https:\/\/ubisasia.com\/?p=8396"},"modified":"2026-03-09T15:52:31","modified_gmt":"2026-03-09T08:52:31","slug":"ubis-new-year-party-2026-movie-night","status":"publish","type":"post","link":"https:\/\/www.ubisasia.com\/zh\/ubis-new-year-party-2026-movie-night\/","title":{"rendered":"\u706f\u5149\u3001\u6444\u5f71\u673a\u3001\u884c\u52a8\uff01\u4f18\u6bd4\u65af\u7535\u5f71\u4e4b\u591c \u0e40\u0e14\u0e47\u0e01\u0e40E28\u21a9\u0e04\u0e37\u0e19\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e40E43\u21a9\u0e19\u0e18\u0e35\u0e21 UBIS Movie Night \u0e07\u0e32\u0e19\u0e1b\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2026"},"content":{"rendered":"<div class=\"row align-center\"  id=\"row-2116583218\">\n\n\n\t<div id=\"col-1092008619\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_404834017\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"700\" height=\"455\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Linkedin-head-postUBIS-ASIA-PUBLIC-CO.-LTD.-700-x-455-px-4.png\" class=\"attachment-large size-large\" alt=\"UBIS Movie Night 2026\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Linkedin-head-postUBIS-ASIA-PUBLIC-CO.-LTD.-700-x-455-px-4.png 700w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Linkedin-head-postUBIS-ASIA-PUBLIC-CO.-LTD.-700-x-455-px-4-300x195.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Linkedin-head-postUBIS-ASIA-PUBLIC-CO.-LTD.-700-x-455-px-4-18x12.png 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Linkedin-head-postUBIS-ASIA-PUBLIC-CO.-LTD.-700-x-455-px-4-510x332.png 510w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_404834017 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"gap-1675352916\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1675352916 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row\"  id=\"row-443912774\">\n\n\n\t<div id=\"col-686861818\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-203744399\" class=\"text\">\n\t\t\n\n<h1><strong>\u706f\u5149\u3001\u6444\u5f71\u673a\u3001\u884c\u52a8\uff01\u4f18\u6bd4\u65af\u7535\u5f71\u4e4b\u591c \u0e40\u0e14\u0e47\u0e01\u0e40E28\u21a9\u0e04\u0e37\u0e19\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e40E43\u21a9\u0e19\u0e18\u0e35\u0e21 UBIS Movie Night \u0e07\u0e32\u0e19\u0e1b\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2026<\/strong><\/h1>\n\t\t\n<style>\n#text-203744399 {\n  color: rgb(0,0,0);\n}\n#text-203744399 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2991473766\" class=\"text\">\n\t\t\n\n<p data-start=\"215\" data-end=\"500\">\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 2026 \u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 <strong data-start=\"222\" data-end=\"291\">\u0639\u0e39\u0e1a\u0e34\u0e2a (\u0e40\u0e2d\u0e40\u0e0a\u0e35\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 (\u0e21\u0e2b\u0e32\u0e0a\u0e19) - ubis (asia) public company limited<\/strong> \u0e9d\u0e9d\u0e9d\u0e9d\u0e9d\u0e9d<strong data-start=\"302\" data-end=\"330\">\u0e40<\/strong>2026 \u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e18\u0e35\u0e21 \u201cUBIS Movie Night\u201d \u0e40\u0e1e\u0e2d\u0e37\u0e2d\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e2d\u0e35\u0e01\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e1b\u0e35\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08 \u0e41\u0e25\u0e30\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e14\u0e49\u0e27\u0e22\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e41\u0e2b\u0e48\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32 \u0e04\u0e27\u0e32\u0e21\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e31\u0e19\u0e02\u0e2d\u0e07\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19<\/p>\n<p data-start=\"502\" data-end=\"743\">\u0e07\u0e32\u0e19\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e1e\u0e34\u0e40\u0e28\u0e29\u0e17\u0e35\u0e48\u0e40\u0e1b\u0e34\u0e14\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e2b\u0e32\u0e01\u0e2b\u0e32\u0e22\u0e41\u0e1c\u0e19\u0e01\u0e44\u0e14\u0e49\u0e21\u0e32\u0e1e\u0e1a\u0e1b\u0e30 \u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e32\u0e17\u0e23\u0e33\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e17\u0e23\u0e07\u0e08\u0e33\u0e14\u0e35 \u0e46\u0e17\u0e35\u0e48\u0e2a\u0e30\u0e17\u0e49\u0e2d\u0e19\u0e16\u0e36\u0e07\u0e27\u0e31\u0e12\u0e19\u0e18\u0e23\u0e23\u0e21\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e02\u0e2d\u0e07 ubis \u0e17\u0e35\u0e48\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e04\u0e19\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e31\u0e21\u0e1e\u0e31\u0e19\u0e18\u0e4c\u0e20\u0e32\u0e22\u0e43\u0e19\u0e17\u0e35\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\n\t\t\n<style>\n#text-2991473766 {\n  color: rgb(0,0,0);\n}\n#text-2991473766 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-542206442\">\n\n\n\t<div id=\"col-1191294683\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_843760936\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-scaled.jpg 2048w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/5-510x340.jpg 510w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_843760936 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1815498331\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1382982795\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-scaled.jpg 2048w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/3-510x340.jpg 510w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1382982795 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-3534048395\" class=\"text\">\n\t\t\n\n<h3 data-path-to-node=\"4\"><b data-path-to-node=\"4\" data-index-in-node=\"0\">\u0e2d\u0e34\u0e48\u0e21\u0e1a\u0e38\u0e0d\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32 \u0e40\u0e2a\u0e23\u0e34\u0e21\u0e2a\u0e34\u0e23\u0e21\u0e07\u0e04\u0e25\u0e43\u0e2b\u0e2d\u0e49\u0e07\u0e04\u0e4c\u0e01\u0e23<\/b><\/h3>\n<p data-path-to-node=\"5\">\u0e40\u0e23\u0e34\u0e48\u0e21\u0e15\u0e49\u0e19\u0e40\u0e0a\u0e49\u0e32\u0e27\u0e31\u0e19\u0e14\u0e35\u0e46 \u0e14\u0e49\u0e27\u0e22\u0e1e\u0e34\u0e18\u0e35\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e28\u0e32\u0e2a\u0e19\u0e32 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e21\u0e2b\u0e32\u0e0a\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e19\u0e33\u0e42\u0e14\u0e22\u0e1b\u0e34\u0e22\u0e04\u0e38\u0e13 \u0e01\u0e24\u0e15\u0e22\u0e32\u0e19\u0e38\u0e15\u0e38\u0e01\u0e25\u0e17\u0e4c \u0e41\u0e25\u0e30\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e48\u0e23\u0e27\u0e21\u0e01\u0e31\u0e19\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e1e\u0e34\u0e18\u0e35\u0e1e\u0e23\u0e32\u0e2b\u0e21\u0e13\u0e4c\u0e44\u0e2b\u0e27\u0e49\u0e28\u0e32\u0e25\u0e1e\u0e23\u0e30\u0e1e\u0e23\u0e2b\u0e21\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e23\u0e34\u0e21\u0e07\u0e04\u0e25 \u0e15\u0e48\u0e2d\u0e14\u0e49\u0e27\u0e22\u0e1e\u0e34\u0e18\u0e35\u0e2a\u0e07\u0e06\u0e4c \u0e16\u0e27\u0e32\u0e22\u0e2a\u0e31\u0e07\u0e06\u0e17\u0e32\u0e19\u0e41\u0e25\u0e30\u0e20\u0e31\u0e15\u0e15\u0e32\u0e2b\u0e32\u0e23\u0e40\u0e1e\u0e25 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e1e\u0e13\u0e35\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e2a\u0e2d\u0e21\u0e32\u0e40\u0e1e\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e27\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e01\u0e25\u0e33\u0e07\u0e43\u0e08\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19<\/p>\n\t\t\n<style>\n#text-3534048395 {\n  color: rgb(0, 0, 0);\n}\n#text-3534048395 > * {\n  color: rgb(0, 0, 0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-828513015\">\n\n\n\t<div id=\"col-625727025\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1153087329\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-26-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1153087329 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-278194394\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_2021429366\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_2021429366 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-1520144161\" class=\"text\">\n\t\t\n\n<h2 data-section-id=\"90alzu\" data-start=\"1170\" data-end=\"1224\">\u0e0a\u0e48\u0e27\u0e07\u0e1a\u0e48\u0e32\u0e22\u0e01\u0e31\u0e1a\u0e01\u0e34\u0e08\u0e23\u0e21 \u7535\u5f71\u4e4b\u591c \u0e17\u0e35\u0e48\u0e40\u0e15\u0e47\u0e21\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e23\u0e2d\u0e22\u0e34\u0e49\u0e21<\/h2>\n<p data-start=\"1226\" data-end=\"1381\">\u0e2b\u0e31\u0e25\u0e07\u0e08\u0e32\u0e01\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e2a\u0e34\u0e49\u0e19\u0e1e\u0e34\u0e18\u0e35\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e0a\u0e49\u0e32\u0e01\u0e47\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e0a\u0e27\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32\u0e19\u0e17\u0e35\u0e48\u0e1f\u0e25\u0e32\u0e22\u0e19\u0e04\u0e23\u0e2d\u0e04\u0e2d\u0e22\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e08\u0e34\u0e01\u0e23\u0e23\u0e21\u0e17\u0e35\u0e48\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e04\u0e2d\u0e37\u7535\u5f71\u5bbe\u679c\u0e17\u0e35\u0e48\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e25\u0e38\u0e49\u0e19\u0e41\u0e25\u0e30\u0e2a\u0e19\u0e38\u0e25\u0e32\u0e01\u0e1b\u0e31\u0e1a\u0e40\u0e01\u0e21 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e01\u0e08\u0e34\u0e01\u0e23\u0e23\u0e21\u0e08\u0e31\u0e1a\u0e09\u0e2b\u0e32\u0e01\u0e25\u0e38\u0e49\u0e19\u0e23\u0e31\u0e1a\u0e02\u0e2d\u0e07\u0e23\u0e32\u0e07\u0e27\u0e31\u0e25\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e04\u0e27\u0e21\u0e15\u0e37\u0e48\u0e19\u0e40\u0e15\u0e49\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e15\u0e25\u0e2d\u0e14\u0e0a\u0e48\u0e27\u0e1a\u0e32\u0e22<\/p>\n<p data-start=\"1570\" data-end=\"1711\">\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e22\u0e31\u0e07\u0e21\u0e35\u0e42\u0e0b\u0e19\u0e02\u0e19\u0e41\u0e25\u0e30\u0e02\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e07\u0e43\u0e2b\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e44\u0e14\u0e49\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19 \u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22 \u0e41\u0e25\u0e30\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1c\u0e48\u0e2d\u0e19\u0e04\u0e25\u0e32\u0e22 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e01\u0e08\u0e01\u0e23\u0e21\u0e23\u0e31\u0e1a\u0e0a\u0e21\u0e20\u0e32\u0e1e\u0e22\u0e19\u0e15\u0e23\u0e4c\u0e41\u0e25\u0e30\u0e23\u0e49\u0e2d\u0e07\u0e04\u0e32\u0e23\u0e32\u0e42\u0e2d\u0e40\u0e01\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2a\u0e19\u0e38\u0e01\u0e2a\u0e19\u0e32\u0e19\u0e15\u0e2d\u0e14\u0e1a\u0e48\u0e32\u0e22<\/p>\n\t\t\n<style>\n#text-1520144161 {\n  color: rgb(0,0,0);\n}\n#text-1520144161 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1006628746\">\n\n\n\t<div id=\"col-1726409012\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_496489230\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-638-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_496489230 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-91271488\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1859905737\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-682-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1859905737 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-1841172035\" class=\"text\">\n\t\t\n\n<p data-section-id=\"90alzu\" data-start=\"1170\" data-end=\"1224\">\u0e44\u0e2e\u0e44\u0e25\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e07\u0e32\u0e19\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e35\u0e49\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e44\u0e14\u0e49\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e15\u0e49\u0e2d\u0e19\u0e23\u0e31\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e08\u0e32\u0e01\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e43\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e17\u0e31\u0e49\u0e07 4 \u0e41\u0e2b\u0e48\u0e07\u0e17\u0e35\u0e48\u0e21\u0e32\u0e23\u0e48\u0e27\u0e21\u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e2d\u0e1a\u0e2d\u0e38\u0e48\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 <strong>\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e01\u0e24\u0e15\u0e31\u0e19\u0e17\u0e4c \u0e42\u0e2e\u0e25\u0e14\u0e34\u0e49\u0e07\u0e2a\u0e4c \u0e08\u0e33\u0e01\u0e31\u0e14 (krittanan holdings), \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e21\u0e15\u0e49\u0e32 \u0e40\u0e21\u0e15\u0e49\u0e32\u0e2d\u0e34\u0e4a\u0e07\u0e04\u0e4c \u0e42\u0e01\u0e25\u0e14\u0e4c (\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e08\u0e33\u0e01\u0e31\u0e14 (meta ink gold (thailand))\u3001\u0e41\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e17\u0e22\u0e17\u0e49\u0e2d\u0e1b\u0e42\u0e04\u0e49\u0e17 \u0e01\u0e23\u0e38\u0e4a\u0e1b \u0e08\u0e33\u0e01\u0e31\u0e14 (thai top coat group) \u0e41\u0e25\u0e30 \u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17 \u0e40\u0e02\u0e21 \u0e40\u0e04\u0e21\u0e34\u0e04\u0e2d\u0e25 \u0e41\u0e04\u0e19 \u0e08\u0e33\u0e01\u0e31\u0e14 (kame chemical can)<\/strong> \u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e40\u0e02\u0e49\u0e32\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e02\u0e2d\u0e07 UBIS \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e21\u0e32\u0e23\u0e27\u0e21\u0e15\u0e31\u0e27\u0e01\u0e31\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e01\u0e32\u0e23\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e2a\u0e31\u0e0d\u0e0d\u0e32\u0e13\u0e27\u0e48\u0e32\u0e43\u0e19\u0e1b\u0e35 2026 \u0e19\u0e35\u0e49 \u0e40\u0e23\u0e32\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e08\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e41\u0e25\u0e30\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e17\u0e35\u0e48\u0e41\u0e02\u0e47\u0e07\u0e41\u0e01\u0e23\u0e48\u0e07<\/p>\n\t\t\n<style>\n#text-1841172035 {\n  color: rgb(0,0,0);\n}\n#text-1841172035 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-620811603\">\n\n\n\t<div id=\"col-1185756624\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_226140897\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-517-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_226140897 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-701625798\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1698288668\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-507-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1698288668 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-1688844146\" class=\"text\">\n\t\t\n\n<h2 data-section-id=\"m5rotx\" data-start=\"2286\" data-end=\"2338\">\u0e1b\u0e34\u0e14\u0e17\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e14\u0e49\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e41\u0e25\u0e30\u0e01\u0e08\u0e34\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e38\u0e14\u0e2a\u0e19\u0e38\u0e01\u21aaE43\u21a9\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e04\u0e48\u0e33<\/h2>\n<p data-start=\"2340\" data-end=\"2518\">\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e22\u0e47\u0e19 \u0e21\u0e15\u0e34\u0e32\u0e28\u0e02\u0e07\u0e2d\u0e07\u0e32\u0e19\u0e01\u0e47\u0e22\u0e48\u0e34\u0e07\u0e04\u0e07\u0e36\u0e01\u0e04\u0e31\u0e21\u0e32\u0e01\u0e02\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e07\u0e32\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e31\u0e07\u0e2a\u0e23\u0e04\u0e4c\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e17\u0e48\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e17\u0e38\u0e01\u0e04\u0e19\u0e44\u0e14\u0e21\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e41\u0e25\u0e30\u0e40\u0e09\u0e25\u0e34\u0e19\u0e40\u0e25\u0e35\u0e49\u0e22\u0e07\u0e2a\u0e23\u0e31\u0e19\u0e40\u0e2a\u0e35\u0e49\u0e22\u0e27\u0e21\u0e21\u0e32\u0e19\u0e17\u0e38\u0e01\u0e04\u0e19\u0e44\u0e14\u0e21\u0e49\u0e32\u0e23\u0e27\u0e21\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e17\u0e32\u0e19\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e1e\u0e39\u0e14\u0e04\u0e38\u0e22\u0e41\u0e25\u0e30\u0e40\u0e09\u0e25\u0e34\u0e21\u0e09\u0e25\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e40\u0e23\u0e47\u0e08\u0e02\u0e2d\u0e07\u0e1b\u0e35\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22\u0e01\u0e31\u0e19 \u0e40\u0e2a\u0e35\u0e22\u0e07\u0e2b\u0e31\u0e27\u0e40\u0e23\u0e32\u0e30\u0e41\u0e25\u0e30\u0e23\u0e2d\u0e22\u0e22\u0e34\u0e49\u0e21\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e19\u0e15\u0e25\u0e2d\u0e14\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e1a\u0e1b\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e08\u0e32\u0e01\u0e41\u0e1c\u0e19\u0e01\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e2b\u0e2d\u0e37\u0e01\u0e32\u0e23\u0e48\u0e27\u0e21\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e01\u0e34\u0e08\u0e01\u0e23\u0e21\u0e1a\u0e19\u0e40\u0e27\u0e17\u0e35<\/p>\n<p data-start=\"2640\" data-end=\"2915\">\u0e2b\u0e19\u0e2b\u0e19\u0e2b\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e07\u0e04\u0e48\u0e33\u0e04\u0e19\u0e04\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e01\u0e27\u0e14\u0e01\u0e32\u0e23\u0e41\u0e15\u0e48\u0e07\u0e01\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e35\u0e19\u0e49\u0e08\u0e31\u0e14\u0e2b\u0e19\u0e02\u0e49\u0e19\u0e20\u0e32\u0e22\u0e43\u0e15\u0e49\u0e18\u0e35\u0e21 Movie Night \u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e08\u0e31\u0e14\u0e40\u0e15\u0e47\u0e21\u0e01\u0e31\u0e1a\u0e0a\u222e\u0e14\u0e17\u0e31\u0e49\u0e07\u0e15\u0e31\u0e25\u0e27\u0e30\u0e04\u0e23\u0e2e\u0e35\u0e42\u0e23\u0e48 \u0e41\u0e1f\u0e19\u0e15\u0e32\u0e0b\u0e35\u0e41\u0e25\u0e30\u0e04\u0e32\u0e41\u0e23\u0e01\u0e40\u0e15\u0e23\u0e4c\u0e2a\u0e38\u0e14\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e04\u0e4c \u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e35\u0e2a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e40\u0e0a\u0e35\u0e22\u0e23\u0e4c\u0e08\u0e32\u0e01\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e17\u0e31\u0e48\u0e27\u0e17\u0e31\u0e49\u0e07\u0e07\u0e32\u0e19<\/p>\n\t\t\n<style>\n#text-1688844146 {\n  color: rgb(0,0,0);\n}\n#text-1688844146 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"slider-wrapper relative\" id=\"slider-365086997\" >\n    <div class=\"slider slider-nav-dots-simple slider-nav-circle slider-nav-normal slider-nav-dark slider-nav-outside slider-style-normal\"\n        data-flickity-options='{            \"cellAlign\": \"center\",            \"imagesLoaded\": true,            \"lazyLoad\": 1,            \"freeScroll\": false,            \"wrapAround\": true,            \"autoPlay\": 6000,            \"pauseAutoPlayOnHover\" : true,            \"prevNextButtons\": true,            \"contain\" : true,            \"adaptiveHeight\" : true,            \"dragThreshold\" : 10,            \"percentPosition\": true,            \"pageDots\": true,            \"rightToLeft\": false,            \"draggable\": true,            \"selectedAttraction\": 0.1,            \"parallax\" : 0,            \"friction\": 0.6        }'\n        >\n        \n\n<div class=\"row\"  id=\"row-81311841\">\n\n\n\t<div id=\"col-1737426396\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1567379032\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-566-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1567379032 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2071010270\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_391186274\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-524-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_391186274 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1645875067\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1014395393\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1014395393 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-432640745\">\n\n\n\t<div id=\"col-325106283\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_152832241\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-840-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_152832241 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1363305908\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1220455706\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-984-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1220455706 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1181294454\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1665465951\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-991-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1665465951 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1636952583\">\n\n\n\t<div id=\"col-359373229\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1186941688\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-788-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1186941688 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-921847634\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_42107498\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-901-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_42107498 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1129365974\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_890467459\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-750-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_890467459 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1829261179\">\n\n\n\t<div id=\"col-883239361\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_608021678\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-726-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_608021678 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-941801808\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1917232070\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-729-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1917232070 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-916237833\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_153625212\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:75%;\">\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"680\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-18x12.jpg 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/UBIS-Movie-Night-456-2.jpg 2048w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_153625212 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n     <\/div>\n\n     <div class=\"loading-spin dark large centered\"><\/div>\n\n\t<\/div>\n\n\n<p style=\"text-align: center;\">\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e01\u0e08\u0e34\u0e01\u0e23\u0e23\u0e21<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>\u706f\u5149\u3001\u6444\u5f71\u673a\u3001\u884c\u52a8\uff01\u4f18\u6bd4\u65af\u7535\u5f71\u4e4b\u591c \u0e40\u0e14\u0e47\u0e01\u0e40E28\u21a9\u0e04\u0e37\u0e19\u0e1b\u0e25\u0e48\u0e2d\u0e22\u0e02\u0e2d\u0e07\u0e40\u0e14\u0e47\u0e01\u0e40E43\u21a9\u0e19\u0e18\u0e35\u0e21 UBIS Movie Night \u0e07\u0e32\u0e19\u0e1b\u0e35\u0e43\u0e2b\u0e21\u0e48\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35 2026<\/p>","protected":false},"author":3,"featured_media":8397,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[71,19],"tags":[103,224,223],"class_list":["post-8396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internal-activities","category-newsletters","tag-ubis","tag-new-year","tag-new-year-party"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/posts\/8396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/comments?post=8396"}],"version-history":[{"count":15,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/posts\/8396\/revisions"}],"predecessor-version":[{"id":8440,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/posts\/8396\/revisions\/8440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/media\/8397"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/media?parent=8396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/categories?post=8396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/tags?post=8396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}