{"id":7813,"date":"2025-10-06T10:52:13","date_gmt":"2025-10-06T03:52:13","guid":{"rendered":"https:\/\/ubisasia.com\/?page_id=7813"},"modified":"2025-10-06T10:57:20","modified_gmt":"2025-10-06T03:57:20","slug":"cannex-1","status":"publish","type":"page","link":"https:\/\/www.ubisasia.com\/zh\/cannex-1\/","title":{"rendered":"Food &#038; Beverage Compound QR code #3"},"content":{"rendered":"<section class=\"section\" id=\"section_2014398041\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-1468066165\">\n\n\n\t<div id=\"col-2049801951\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-574605666\" class=\"text\">\n\t\t\n\n<h3><strong>\u4e4c\u6bd4\u65af\uff08\u4e9a\u6d32\uff09\u4ea7\u54c1<\/strong><\/h3>\n\t\t\n<style>\n#text-574605666 {\n  font-size: 0.75rem;\n  color: #086037;\n}\n#text-574605666 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1733522182\" class=\"text\">\n\t\t\n\n<h1><strong>\u4ea7\u54c1<\/strong><\/h1>\n\t\t\n<style>\n#text-1733522182 {\n  color: rgb(0,0,0);\n}\n#text-1733522182 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row align-center\"  id=\"row-478873946\">\n\n\n\t<div id=\"col-1502212515\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1753491902\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-4.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-4.png 940w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-4-300x251.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-4-768x644.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-4-510x428.png 510w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1753491902 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3 style=\"text-align: center;\"><a href=\"\/zh\/food-bev-compound-sealants-infographic\/\">\u590d\u5408\u5bc6\u5c01\u5242<\/a><\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1455511828\" class=\"col medium-6 small-12 large-6\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1302328810\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER.png 940w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-300x251.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-768x644.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Food-General-Line-Cans-EXTERIOR-LACQUER-510x428.png 510w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_1302328810 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n<h3 style=\"text-align: center;\"><a href=\"\/zh\/exterior-lacquer-infographic\/\">\u5916\u6f06<\/a><\/h3>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2014398041 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":930,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7813","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/pages\/7813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/comments?post=7813"}],"version-history":[{"count":6,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/pages\/7813\/revisions"}],"predecessor-version":[{"id":7821,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/pages\/7813\/revisions\/7821"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/zh\/wp-json\/wp\/v2\/media?parent=7813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}