{"id":8102,"date":"2025-11-19T15:38:03","date_gmt":"2025-11-19T08:38:03","guid":{"rendered":"https:\/\/ubisasia.com\/?page_id=8102"},"modified":"2026-07-09T10:27:27","modified_gmt":"2026-07-09T03:27:27","slug":"factory-operations","status":"publish","type":"page","link":"https:\/\/www.ubisasia.com\/th\/people\/factory-operations\/","title":{"rendered":"\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19"},"content":{"rendered":"<div class=\"banner has-hover bg-overlay-remove\" id=\"banner-504446487\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1800\" height=\"600\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/factory-operation.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-1369841529\" class=\"text-box banner-layer x50 md-x90 lg-x90 y50 md-y65 lg-y65 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-2578243013\" class=\"text\">\n\t\t\n\n<h2 class=\"p1\"><strong>Factory Operation<\/strong><\/h2>\n<p class=\"p1\">Turning vision into production<\/p>\n\t\t\n<style>\n#text-2578243013 {\n  font-size: 1rem;\n  line-height: 1.1;\n  text-align: left;\n  color: #086037;\n}\n#text-2578243013 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1369841529 {\n  width: 80%;\n}\n#text-box-1369841529 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-1369841529 {\n    width: 40%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-504446487 {\n  padding-top: 400px;\n}\n#banner-504446487 .overlay {\n  background-color: rgba(255, 255, 255, 0.558);\n}\n@media (min-width:550px) {\n  #banner-504446487 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_784244732\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-1824119267\">\n\n\n\t<div id=\"col-1584100117\" class=\"col medium-10 small-12 large-12\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-31282206\" class=\"gap-element clearfix 50\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-31282206 {\n  padding-top: 32px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-53120919\" class=\"text\">\n\t\t\n\n<p><a href=\"\/th\/people\/\">\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32<\/a> | <strong>Factory Operation<\/strong><\/p>\n\t\t\n<style>\n#text-53120919 {\n  color: #086037;\n}\n#text-53120919 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1250147229\" class=\"text\">\n\t\t\n\n<p><strong>\u0e17\u0e35\u0e48 UBIS, <\/strong>\u0e17\u0e35\u0e21\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22. \u0e40\u0e23\u0e32\u0e40\u0e25\u0e48\u0e19\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e15\u0e32\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e02\u0e49\u0e21\u0e07\u0e27\u0e14\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22, \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e, \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19.<\/p>\n<p>\u0e43\u0e19\u0e10\u0e32\u0e19\u0e30\u0e1e\u0e31\u0e19\u0e18\u0e21\u0e34\u0e15\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23 \u0e17\u0e35\u0e21\u0e07\u0e32\u0e19\u0e17\u0e33\u0e07\u0e32\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e01\u0e25\u0e49\u0e0a\u0e34\u0e14\u0e01\u0e31\u0e1a\u0e1d\u0e48\u0e32\u0e22\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32 \u0e1d\u0e48\u0e32\u0e22\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e1d\u0e48\u0e32\u0e22\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2d\u0e32\u0e0a\u0e35\u0e27\u0e2d\u0e19\u0e32\u0e21\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e1d\u0e48\u0e32\u0e22\u0e0b\u0e31\u0e1e\u0e1e\u0e25\u0e32\u0e22\u0e40\u0e0a\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23 \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e1c\u0e25\u0e2a\u0e39\u0e07\u0e2a\u0e38\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07 \u0e40\u0e23\u0e32\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e25\u0e31\u0e1e\u0e18\u0e4c\u0e17\u0e35\u0e48\u0e08\u0e31\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e25\u0e39\u0e01\u0e04\u0e49\u0e32\u0e41\u0e25\u0e30\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08.<\/p>\n\t\t\n<style>\n#text-1250147229 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1584100117 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_784244732 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_2110357922\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-1057940316\">\n\n\n\t<div id=\"col-75566117\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"ux-lottie-557495719\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/ubisasia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/testing-ibis-1.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-557495719&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-557495719 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-524258793\" class=\"col medium-6 small-12 large-6\"  data-animate=\"bounceIn\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3837098368\" class=\"text\">\n\t\t\n\n<h3 class=\"p1\"><strong>\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e23\u0e31\u0e01\u0e1c\u0e34\u0e14\u0e0a\u0e2d\u0e1a<\/strong><\/h3>\n\t\t\n<style>\n#text-3837098368 {\n  color: #086037;\n}\n#text-3837098368 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n<ul>\n<li>\n<p>\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e34\u0e08\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19<\/p>\n<\/li>\n<li>\n<p>\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e15\u0e32\u0e21\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e2a\u0e34\u0e48\u0e07\u0e41\u0e27\u0e14\u0e25\u0e49\u0e2d\u0e21 \u0e41\u0e25\u0e30\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e<\/p>\n<\/li>\n<li>\n<p>\u0e01\u0e32\u0e23\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e1c\u0e25\u0e1c\u0e25\u0e34\u0e15<\/p>\n<\/li>\n<li>\n<p>\u0e23\u0e48\u0e27\u0e21\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e17\u0e35\u0e21\u0e02\u0e49\u0e32\u0e21\u0e2a\u0e32\u0e22\u0e07\u0e32\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15<\/p>\n<\/li>\n<li>\n<p>\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e34\u0e40\u0e23\u0e34\u0e48\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e15\u0e48\u0e2d\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07<\/p>\n<\/li>\n<li>\n<p>\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e41\u0e25\u0e30\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1d\u0e48\u0e32\u0e22\u0e1c\u0e25\u0e34\u0e15<\/p>\n<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2110357922 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1624670167\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-237575379\">\n\n\n\t<div id=\"col-1762880429\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-2100496225\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2100496225 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row align-center\"  id=\"row-903089417\">\n\n\n\t<div id=\"col-351129381\" class=\"col medium-8 small-12 large-8\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-42008419\" class=\"text\">\n\t\t\n\n<h2><strong><span class=\"brand-color-primary\">Career Growth<\/span><\/strong><\/h2>\n\t\t\n<style>\n#text-42008419 {\n  font-size: 1.5rem;\n  text-align: center;\n  color: #086037;\n}\n#text-42008419 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-351129381 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-528630126\">\n\n\n\t<div id=\"col-1955134516\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-448518437\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-448518437 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"ux-lottie-2160002934\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/ubisasia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/career-growth-2-2.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-2160002934&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-2160002934 {\n  width: 100%;\n  height: 150px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-1813060195\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1813060195 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2155718469\" class=\"text\">\n\t\t\n\n<p class=\"p1\">\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e01\u0e32\u0e23\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e07\u0e32\u0e19\u0e43\u0e19\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15, \u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e25\u0e35\u0e19, \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e20\u0e32\u0e27\u0e30\u0e1c\u0e39\u0e49\u0e19\u0e33. \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e41\u0e25\u0e30\u0e17\u0e31\u0e01\u0e29\u0e30\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e17\u0e35\u0e21\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e41\u0e25\u0e30\u0e01\u0e49\u0e32\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e19\u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07\u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15.<\/p>\n\t\t\n<style>\n#text-2155718469 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1955134516 > .col-inner {\n  margin: 0px 0px -40px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1624670167 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1624670167 .section-bg-overlay {\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1941323998\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;margin:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-2020740950\">\n\n\n\t<div id=\"col-1211063936\" class=\"col medium-10 small-12 large-8\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2415799908\" class=\"text\">\n\t\t\n\n<h2><strong>UBIS Disciplines<\/strong><\/h2>\n\t\t\n<style>\n#text-2415799908 {\n  font-size: 1.5rem;\n  text-align: center;\n  color: #086037;\n}\n#text-2415799908 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:6000px;height:2px;\"><\/div>\n\n\t<div id=\"text-2716986701\" class=\"text\">\n\t\t\n\n<p class=\"p1\">\u0e1d\u0e48\u0e32\u0e22\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e42\u0e23\u0e07\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 UBIS \u0e08\u0e30\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d \u0e1d\u0e48\u0e32\u0e22\u0e19\u0e35\u0e49\u0e21\u0e35\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1a\u0e23\u0e23\u0e25\u0e38\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e43\u0e19\u0e02\u0e13\u0e30\u0e17\u0e35\u0e48\u0e22\u0e31\u0e07\u0e04\u0e07\u0e23\u0e31\u0e01\u0e29\u0e32\u0e21\u0e32\u0e15\u0e23\u0e10\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e19\u0e48\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e16\u0e37\u0e2d.<\/p>\n<p><strong>\u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e2b\u0e25\u0e32\u0e22\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d:<\/strong><\/p>\n\t\t\n<style>\n#text-2716986701 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1211063936 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-1267747396\">\n\n\n\t<div id=\"col-1624050615\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-2137896034\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2137896034 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Management.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-649397688\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><b>Production Management<\/b><\/h4>\n\t\t\n<style>\n#text-649397688 {\n  text-align: center;\n  color: #086037;\n}\n#text-649397688 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-428398797\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-428398797 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p class=\"p1\">\u0e14\u0e39\u0e41\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e21\u0e31\u0e48\u0e19\u0e43\u0e08\u0e27\u0e48\u0e32\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e16\u0e39\u0e01\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e15\u0e23\u0e07\u0e40\u0e27\u0e25\u0e32 \u0e41\u0e25\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e02\u0e49\u0e2d\u0e01\u0e33\u0e2b\u0e19\u0e14.<\/p>\n\t<div id=\"gap-1049756030\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1049756030 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1624050615 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1018356108\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1087355133\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1087355133 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Production-Planning.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2576781707\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><strong>Production\u00a0<\/strong><b>Planning<\/b><\/h4>\n\t\t\n<style>\n#text-2576781707 {\n  text-align: center;\n  color: #086037;\n}\n#text-2576781707 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-47470056\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-47470056 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p class=\"p1\">\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e27\u0e25\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e07\u0e32\u0e19\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23 \u0e27\u0e31\u0e2a\u0e14\u0e38 \u0e41\u0e25\u0e30\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e01\u0e32\u0e23\u0e44\u0e2b\u0e25\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e41\u0e25\u0e30\u0e15\u0e2d\u0e1a\u0e2a\u0e19\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e17\u0e32\u0e07\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08.<\/p>\n\t<div id=\"gap-1247280953\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1247280953 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1018356108 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-401083214\" class=\"col medium-4 small-12 large-4\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1445363154\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1445363154 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Process-Engineering.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-355688515\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><strong>Process Engineering<\/strong><\/h4>\n\t\t\n<style>\n#text-355688515 {\n  text-align: center;\n  color: #086037;\n}\n#text-355688515 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-936163354\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-936163354 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p class=\"p1\">\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a \u0e1b\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e38\u0e07 \u0e41\u0e25\u0e30\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e \u0e25\u0e14\u0e02\u0e2d\u0e07\u0e40\u0e2a\u0e35\u0e22 \u0e41\u0e25\u0e30\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e01\u0e31\u0e19\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e1c\u0e25\u0e34\u0e15\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e17\u0e35\u0e48\u0e2a\u0e21\u0e48\u0e33\u0e40\u0e2a\u0e21\u0e2d.<\/p>\n\t<div id=\"gap-332313091\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-332313091 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-401083214 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1941323998 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1941323998 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\t<section class=\"section\" id=\"section_769106470\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/07\/S__33406994-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1129502867\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1024x576.webp\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-205023542\" class=\"text-box banner-layer x85 md-x95 lg-x95 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-3166015464\" class=\"text\">\n\t\t\n\n<h2 class=\"uppercase\"><strong>\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32<\/strong><\/h2>\n\t\t\n<style>\n#text-3166015464 {\n  text-align: center;\n  color: #086037;\n}\n#text-3166015464 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-486557954\" class=\"text\">\n\t\t\n\n<h5>\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e04\u0e23\u0e31\u0e49\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e48\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e44\u0e1b\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e04\u0e25\u0e34\u0e01\u0e40\u0e14\u0e35\u0e22\u0e27<\/h5>\n\t\t\n<style>\n#text-486557954 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<a data-animate=\"fadeInLeft\" href=\"https:\/\/forms.cloud.microsoft\/pages\/responsepage.aspx?id=wfacPzJGYkuvbyn0aNXToPsbEW4aN3pDsQP3qJmcr7JUNjQ5OU9XWUU1VFBKUTBWSVoyVElQN0RYVi4u&#038;route=shorturl\" target=\"_blank\" class=\"button primary\" rel=\"noopener\">\n\t\t<span>work with us<\/span>\n\t<\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-205023542 {\n  width: 68%;\n}\n#text-box-205023542 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-205023542 {\n    width: 44%;\n  }\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-1405581424\" class=\"text-box banner-layer x5 md-x5 lg-x5 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div class=\"img has-hover hide-for-small x md-x lg-x y md-y lg-y\" id=\"image_829746024\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-fade-in dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1024x576.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1024x576.webp 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-300x169.webp 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-768x432.webp 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1536x864.webp 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-scaled.webp 2048w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-510x287.webp 510w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_829746024 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1405581424 {\n  width: 41%;\n}\n#text-box-1405581424 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1129502867 {\n  padding-top: 300px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1129502867 .overlay {\n  background-color: rgba(246, 246, 246, 0.901);\n}\n@media (min-width:550px) {\n  #banner-1129502867 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_769106470 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_769106470 .section-bg-overlay {\n  background-color: rgba(2, 104, 56, 0.878);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1340,"parent":44,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8102","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/pages\/8102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/comments?post=8102"}],"version-history":[{"count":6,"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/pages\/8102\/revisions"}],"predecessor-version":[{"id":8798,"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/pages\/8102\/revisions\/8798"}],"up":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/pages\/44"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/media\/1340"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/th\/wp-json\/wp\/v2\/media?parent=8102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}