{"id":1137,"date":"2025-08-14T10:04:17","date_gmt":"2025-08-14T03:04:17","guid":{"rendered":"https:\/\/ubisasia.com\/?post_type=product&#038;p=1137"},"modified":"2025-10-14T15:23:45","modified_gmt":"2025-10-14T08:23:45","slug":"ubis-polyurethane-solvent-based","status":"publish","type":"product","link":"https:\/\/www.ubisasia.com\/es\/producto\/ubis-polyurethane-solvent-based\/","title":{"rendered":"POLIURETANO UBIS (BASE DISOLVENTE)"},"content":{"rendered":"<h3><b>Poliuretano (base disolvente)<\/b><\/h3>\n<p>El adhesivo UBIS PU de base disolvente es un sistema de tipo poliuretano que utiliza disolventes org\u00e1nicos como portadores. Dise\u00f1amos este adhesivo espec\u00edficamente para laminar films de envasado flexibles como PET\/PE, PET\/CPP, OPP\/CPP, OPP\/VMCPP y Nylon\/PE. Este potente adhesivo proporciona una excelente fuerza de uni\u00f3n, transparencia y durabilidad, lo que lo hace adecuado para una amplia gama de aplicaciones de envasado, incluidos los alimentos, el cuidado personal y los productos industriales.<\/p>\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"margin-top:20px;margin-bottom:20px;max-width:100%;height:1px;background-color:rgb(0, 0, 0);\"><\/div><\/div>\n<div class=\"row row-divided\"  id=\"row-1737632232\">\n\n\t<div id=\"col-392413012\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>CARACTER\u00cdSTICAS<\/strong><\/p>\n<div>\n<ul>\n<li><b>Tipo de sistema:<\/b>\u00a0Funciona como un adhesivo de poliuretano de dos componentes a base de disolvente (principal + endurecedor).<\/li>\n<li><b>Acci\u00f3n curativa:<\/b>\u00a0Consigue su uni\u00f3n mediante una reacci\u00f3n qu\u00edmica de reticulaci\u00f3n.<\/li>\n<li><b>Calidad de la pel\u00edcula:<\/b>\u00a0Produce una pel\u00edcula final flexible, transparente y no quebradiza.<\/li>\n<li><b>Control de la viscosidad:<\/b>\u00a0Se ajusta f\u00e1cilmente en funci\u00f3n de la proporci\u00f3n de disolvente elegida.<\/li>\n<li><b>Compatibilidad con pel\u00edculas:<\/b>\u00a0Funciona perfectamente con PET, BOPP, CPP, Nylon, PE y pel\u00edculas metalizadas.<\/li>\n<li><b>Velocidad de la m\u00e1quina:<\/b>\u00a0Admite el funcionamiento a alta velocidad, hasta 400-600 m\/min.<\/li>\n<li><b>Rendimiento t\u00e9rmico:<\/b>\u00a0Ofrece una excelente resistencia al calor.<\/li>\n<li><b>Defensa qu\u00edmica:<\/b>\u00a0Ofrece una excelente resistencia al aceite, la grasa, el alcohol y los productos qu\u00edmicos suaves.<\/li>\n<\/ul>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1193591324\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>VENTAJAS<\/strong><\/p>\n<ul>\n<li><b>Consigue una alta fuerza de adhesi\u00f3n:<\/b> El adhesivo se adhiere excelentemente a diversas estructuras de pel\u00edcula.<\/li>\n<li><b>Cree laminados transparentes y brillantes:<\/b>\u00a0El sistema proporciona una gran transparencia y realza el atractivo visual.<\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Aumente la eficiencia de la producci\u00f3n:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0<\/span>Secado y curado r\u00e1pidos<span style=\"color: #555555; font-size: 14.4px;\"> dram\u00e1ticamente <\/span>aumentar<span style=\"color: #555555; font-size: 14.4px;\"> producci\u00f3n.<\/span><\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Manejar altas temperaturas y productos qu\u00edmicos:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0El adhesivo <\/span>resiste<span style=\"color: #555555; font-size: 14.4px;\"> calor y los productos qu\u00edmicos, por lo que es ideal para <\/span>aplicaciones de retorta y llenado en caliente<span style=\"color: #555555; font-size: 14.4px;\">.<\/span><\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Garantiza un rendimiento estable:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0El adhesivo <\/span>mantiene<span style=\"color: #555555; font-size: 14.4px;\"> calidad y fiabilidad constantes durante largas tiradas de producci\u00f3n.<\/span><\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Permitir un funcionamiento estable:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0Larga vida \u00fatil <\/span>garantiza un funcionamiento estable<span style=\"color: #555555; font-size: 14.4px;\"> despu\u00e9s de mezclar.<\/span><\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-927003069\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<p><strong>SOLICITUD<\/strong><\/p>\n<ul>\n<li><b>Embalaje general:<\/b>\u00a0Lamina estructuras de pel\u00edcula como OPP\/CPP y PET\/CPP para art\u00edculos como aperitivos y alimentos secos.<\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Envasado Retort:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0<\/span>Crea<span style=\"color: #555555; font-size: 14.4px;\"> estructuras duraderas de PET\/AL\/CPP adecuadas para comidas listas para el consumo y otras aplicaciones de alta temperatura.<\/span><\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Envasado l\u00edquido:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0<\/span>Bonos<span style=\"color: #555555; font-size: 14.4px;\"> L\u00e1minas de PET\/PE para envases de zumos y salsas.<\/span><\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Alimentos congelados:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0<\/span>Funciona eficazmente<span style=\"color: #555555; font-size: 14.4px;\"> en estructuras de PET\/PE y NY\/PE dise\u00f1adas para diversos alimentos congelados.<\/span><\/li>\n<li><b style=\"color: #555555; font-size: 14.4px;\">Cuidado personal:<\/b><span style=\"color: #555555; font-size: 14.4px;\">\u00a0<\/span>Admite<span style=\"color: #555555; font-size: 14.4px;\"> Laminados OPP\/VMCPP utilizados en el envasado de champ\u00fa, cremas y detergente.<\/span><\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>UBIS Polyurethane solvent based<br \/>\n<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-423\"><form id=\"wpforms-form-423\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"423\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/es\/wp-json\/wp\/v2\/product\/1137\" data-token=\"2fbec9d4e35c409429e1f7b7ad03b127\"><div class=\"wpforms-head-container\"><\/div><noscript class=\"wpforms-error-noscript\">Por favor, activa JavaScript en tu navegador para completar este formulario.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-423-field_2-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-423-field_2\">Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-423-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/div><div id=\"wpforms-423-field_8-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"8\"><label class=\"wpforms-field-label\" for=\"wpforms-423-field_8\">Company Name <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-423-field_8\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][8]\" required><\/div><div id=\"wpforms-423-field_5-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-423-field_5\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-423-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" required><\/div><div id=\"wpforms-423-field_7-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-423-field_7\">Message<\/label><textarea id=\"wpforms-423-field_7\" class=\"wpforms-field-medium\" name=\"wpforms[fields][7]\" ><\/textarea><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"423\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"2\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-423\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"https:\/\/www.ubisasia.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\n","protected":false},"featured_media":1144,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[36,40,56],"product_tag":[],"class_list":["post-1137","product","type-product","status-publish","has-post-thumbnail","product_cat-non-metal-packaging","product_cat-adhesives","product_cat-dry-laminated-adhesive","first","instock","featured","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/product\/1137","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/comments?post=1137"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media\/1144"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media?parent=1137"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/product_brand?post=1137"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/product_cat?post=1137"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/product_tag?post=1137"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}