{"id":291,"date":"2022-06-24T19:23:59","date_gmt":"2022-06-24T12:23:59","guid":{"rendered":"https:\/\/ubisasia.com\/?p=291"},"modified":"2025-09-15T13:55:48","modified_gmt":"2025-09-15T06:55:48","slug":"sealing-compounds","status":"publish","type":"post","link":"https:\/\/www.ubisasia.com\/es\/sealing-compounds\/","title":{"rendered":"Compuestos de sellado"},"content":{"rendered":"<div class=\"row align-center\"  id=\"row-524958612\">\n\n\n\t<div id=\"col-1655422666\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;margin:0px 0px 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_44394667\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"700\" height=\"441\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds_October-17th-2022-1.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds_October-17th-2022-1.jpg 700w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds_October-17th-2022-1-300x189.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds_October-17th-2022-1-510x321.jpg 510w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_44394667 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\t<div id=\"text-2036102664\" class=\"text\">\n\t\t\n\n<h1><strong>Compuestos de sellado<\/strong><\/h1>\n\t\t\n<style>\n#text-2036102664 {\n  color: rgb(0,0,0);\n}\n#text-2036102664 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-152908137\" class=\"text\">\n\t\t\n\n<p><strong>Los compuestos de sellado son una parte vital del envasado, ya que evitan las fugas y la contaminaci\u00f3n en los envases met\u00e1licos. En el caso de las latas de tres piezas, se aplica un sellador de goma especial a las tapas superior e inferior despu\u00e9s de a\u00f1adir el contenido. Este paso crucial no s\u00f3lo impide que los contaminantes externos estropeen el producto, sino que prolonga considerablemente su vida \u00fatil. En el caso de las latas para alimentos, el sellador debe soportar las altas temperaturas del proceso de esterilizaci\u00f3n, garantizando que el alimento siga siendo seguro y de alta calidad.<\/strong><\/p>\n<p>Adem\u00e1s, este sellador de latas tiene que soportar altas temperaturas en el proceso de esterilizaci\u00f3n para preservar la calidad de las latas de alimentos. En la actualidad, existen 2 tipos de sellador de latas como sigue:<\/p>\n<p>1. Sellador de caucho que utiliza agua como material de base (base de agua).\u00a0<a href=\"https:\/\/www.ubisasia.com\/es\/products\/metal-packagings\/compound-sealants\/\" target=\"_blank\" rel=\"noopener\"><u>compuestos de sellado<\/u><\/a>) Es una goma que se produce de acuerdo normas internacionales de la Administraci\u00f3n de Alimentos y Medicamentos (FDA) para su uso con envases de alimentos. que tiene ventajas como ser respetuoso con el medio ambiente, no t\u00f3xico para los consumidores Existen diferentes tipos de sellador en funci\u00f3n de la aplicaci\u00f3n y los productos envasados en latas, ya que cada producto requiere una impermeabilizaci\u00f3n diferente, como latas de alimentos, latas de bebidas, etc. Las latas m\u00e1s comunes son las de aceite. las de aerosol para maquinaria Medicina o los tubos de cosm\u00e9ticos, etc.<\/p>\n<p>2. El sellador de caucho a base de cloruro de polivinilo como material de base (PVC Plastisol) se utiliza para sellar otros envases met\u00e1licos desde envases de 20 litros (Crimp Cap) hasta 200 litros, como cubos de gal\u00f3n para tanques de pintura, para el llenado de aceite, etc. Tambi\u00e9n se utiliza para envases no met\u00e1licos como los tapones corona de las botellas de refresco. Sellador de tap\u00f3n de rosca (RO) o tap\u00f3n retorcido (ROPP) de botellas de bebidas energ\u00e9ticas y sellador de caucho Lug Cap o Twist-Off de tapones de botellas de mermelada.<\/p>\n<p>\u00a0<\/p>\n<p>Sin embargo, la propiedad de los dos tipos de sellador es mantener la calidad de los productos contenidos en el envase impidiendo los contaminantes del medio ambiente retenci\u00f3n de la composici\u00f3n interna de gas Preservar el olor y el color de los productos envasados, as\u00ed como el sabor para que no cambien.<\/p>\n<p>Fuente : <a href=\"https:\/\/www.ubisasia.com\/es\/sealing-compound\/\">Compuesto sellante - UBIS Asia Public Company Limited<\/a><\/p>\n\t\t\n<style>\n#text-152908137 {\n  color: rgb(0,0,0);\n}\n#text-152908137 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_884030499\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"279\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/sealing-compound-oct-1024x280-1.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/sealing-compound-oct-1024x280-1.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/sealing-compound-oct-1024x280-1-510x139.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/sealing-compound-oct-1024x280-1-300x82.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/sealing-compound-oct-1024x280-1-768x210.png 768w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_884030499 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-2354134412\" class=\"text\">\n\t\t\n\n<p>Figura A. Antes de la aplicaci\u00f3n del sellador Figura B. Figura C. Despu\u00e9s de la aplicaci\u00f3n del sellador, tapa (arriba) y tapa (abajo) poner lechada en las ranuras (figura ficticia) en el borde de la tapa.<\/p>\n<p>La figura anterior muestra una vista en secci\u00f3n transversal de una tapa de lata. La figura A muestra una l\u00e1mina met\u00e1lica recubierta. y moldeada en una tapa incluyendo la curvatura de la esquina de la tapa. Las figuras B. y C. muestran la imagen de la aplicaci\u00f3n de sellante a la tapa a lo largo de la ranura curva interior. Evitar las fugas de los productos envasados e impedir la entrada de materias extra\u00f1as en el interior. (Fuente de la imagen: www.cancentral.com y Visypak Beverage Packaging \u201cBeverage Manufacturing Processes\u201d)<\/p>\n<p>Fuente : Sealing Compound - UBIS Asia Public Company Limited<\/p>\n\t\t\n<style>\n#text-2354134412 {\n  color: rgb(0,0,0);\n}\n#text-2354134412 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Sealing compounds are sealants used in metal containers to prevent leaks along the seams. between the container and the lid If it\u2019s a 3-piece can, rubber sealant will be used on both the bottom and top lids after packing food or goods into the container to prevent contamination from outside. This extends the shelf life of the product inside the can.<\/p>","protected":false},"author":3,"featured_media":292,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18,1],"tags":[72,115],"class_list":["post-291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-knowledge-center","category-products","tag-can","tag-sealing-compounds"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/posts\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":2,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/posts\/291\/revisions"}],"predecessor-version":[{"id":7542,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/posts\/291\/revisions\/7542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media\/292"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media?parent=291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/categories?post=291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/tags?post=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}