{"id":8060,"date":"2025-11-19T15:38:52","date_gmt":"2025-11-19T08:38:52","guid":{"rendered":"https:\/\/ubisasia.com\/?page_id=8060"},"modified":"2026-07-09T10:23:13","modified_gmt":"2026-07-09T03:23:13","slug":"sales-and-marketing","status":"publish","type":"page","link":"https:\/\/www.ubisasia.com\/es\/people\/sales-and-marketing\/","title":{"rendered":"Ventas y marketing"},"content":{"rendered":"<div class=\"banner has-hover\" id=\"banner-2087335028\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1800\" height=\"600\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Sales-and-Marketing-.png\" class=\"bg attachment-original size-original\" alt=\"\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-772114640\" class=\"text-box banner-layer x50 md-x100 lg-x100 y50 md-y65 lg-y65 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-2475139209\" class=\"text\">\n\t\t\n\n<h2 class=\"p1\">Ventas y marketing<\/h2>\n<p class=\"p1\">Conectar mercados, crear valor<\/p>\n\t\t\n<style>\n#text-2475139209 {\n  font-size: 1rem;\n  line-height: 1.1;\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-2475139209 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-772114640 {\n  width: 80%;\n}\n#text-box-772114640 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-772114640 {\n    width: 40%;\n  }\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-2087335028 {\n  padding-top: 400px;\n}\n#banner-2087335028 .banner-bg img {\n  object-position: 0% 0%;\n}\n@media (min-width:550px) {\n  #banner-2087335028 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_1296852963\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-107201375\">\n\n\n\t<div id=\"col-81562169\" class=\"col medium-10 small-12 large-12\"  data-animate=\"fadeInRight\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-479112519\" class=\"gap-element clearfix 50\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-479112519 {\n  padding-top: 32px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-407964632\" class=\"text\">\n\t\t\n\n<p><a href=\"\/es\/people\/\">Personas<\/a> | <strong>Ventas y marketing<\/strong><\/p>\n\t\t\n<style>\n#text-407964632 {\n  color: #086037;\n}\n#text-407964632 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-155875739\" class=\"text\">\n\t\t\n\n<p><strong>En la UBIS, <\/strong>nuestro equipo de Ventas y Marketing est\u00e1 a la vanguardia de la conexi\u00f3n de nuestros productos con los clientes y mercados adecuados. Combinamos conocimientos del mercado, creatividad y pensamiento estrat\u00e9gico para impulsar el crecimiento empresarial y crear relaciones duraderas con los clientes.<\/p>\n<div>\u00a0<\/div>\n<div>Como socio de crecimiento, el equipo de Ventas y Marketing trabaja en estrecha colaboraci\u00f3n con I+D, Servicio T\u00e9cnico al Cliente y Operaciones para ofrecer valor, lanzar soluciones innovadoras y reforzar la marca UBIS en todos los mercados en los que operamos.<\/div>\n\t\t\n<style>\n#text-155875739 {\n  text-align: left;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-81562169 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1296852963 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_62477951\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle\"  id=\"row-914245714\">\n\n\n\t<div id=\"col-505022661\" class=\"col medium-6 small-12 large-6\"  data-animate=\"fadeInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"ux-lottie-3166861318\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/ubisasia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/testing-ibis-1.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-3166861318&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-3166861318 {\n  width: 100%;\n  height: 300px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-695433272\" class=\"col medium-6 small-12 large-6\"  data-animate=\"bounceIn\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-4199752047\" class=\"text\">\n\t\t\n\n<h3 class=\"p1\"><strong>Entre otras cosas, ser\u00e1 responsable de :<\/strong><\/h3>\n\t\t\n<style>\n#text-4199752047 {\n  color: #086037;\n}\n#text-4199752047 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n<ul>\n<li>Desarrollar y ejecutar estrategias de ventas y marketing para alcanzar los objetivos empresariales.<\/li>\n<li>Establecer relaciones s\u00f3lidas con los clientes y las principales partes interesadas<\/li>\n<li>Realizaci\u00f3n de estudios de mercado y an\u00e1lisis de tendencias para identificar oportunidades<\/li>\n<li>Apoyo a lanzamientos de productos y campa\u00f1as promocionales<\/li>\n<li>Colaboraci\u00f3n con equipos multifuncionales para mejorar la experiencia del cliente<\/li>\n<li>Impulsar el conocimiento de la marca y la presencia de UBIS en el mercado<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_62477951 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1788370270\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-183203369\">\n\n\n\t<div id=\"col-1197366248\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-623836622\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-623836622 {\n  padding-top: 31px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row align-center\"  id=\"row-1747066449\">\n\n\n\t<div id=\"col-1464936340\" class=\"col medium-8 small-12 large-8\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2723171655\" class=\"text\">\n\t\t\n\n<h2><strong><span class=\"brand-color-primary\">Crecimiento profesional<\/span><\/strong><\/h2>\n\t\t\n<style>\n#text-2723171655 {\n  font-size: 1.5rem;\n  text-align: center;\n  color: #086037;\n}\n#text-2723171655 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1464936340 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-1612004308\">\n\n\n\t<div id=\"col-1211431661\" class=\"col small-12 large-12\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1360718759\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1360718759 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"ux-lottie-3136113053\" class=\"ux-lottie\" >\n\t\t\t\t<lottie-player class=\"ux-lottie__player\" data-params=\"{&quot;src&quot;:&quot;https:\\\/\\\/ubisasia.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/career-growth-2-2.json&quot;,&quot;loop&quot;:true,&quot;autoplay&quot;:true,&quot;controls&quot;:false,&quot;speed&quot;:&quot;1&quot;,&quot;direction&quot;:1,&quot;trigger&quot;:&quot;&quot;,&quot;mouseout&quot;:&quot;&quot;,&quot;start&quot;:0,&quot;end&quot;:100,&quot;scrollActionType&quot;:&quot;seek&quot;,&quot;visibilityStart&quot;:0,&quot;visibilityEnd&quot;:100,&quot;id&quot;:&quot;ux-lottie-3136113053&quot;}\" ><\/lottie-player>\n\t\t\t\t\n<style>\n#ux-lottie-3136113053 {\n  width: 100%;\n  height: 150px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"gap-569442638\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-569442638 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t<div id=\"text-1104738593\" class=\"text\">\n\t\t\n\n<p>Las funciones de Ventas y Marketing proporcionan formaci\u00f3n en ventas estrat\u00e9gicas, gesti\u00f3n de marcas y an\u00e1lisis de mercado. Tambi\u00e9n tendr\u00e1s la oportunidad de asistir a talleres, programas de tutor\u00eda y certificaciones para crecer como l\u00edder empresarial centrado en el mercado.<\/p>\n\t\t\n<style>\n#text-1104738593 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1211431661 > .col-inner {\n  margin: 0px 0px -40px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1788370270 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1788370270 .section-bg-overlay {\n  background-color: rgb(247, 247, 247);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1288678090\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\t<div class=\"is-border\"\n\t\tstyle=\"border-width:0px 0px 0px 0px;margin:0px 0px 0px 0px;\">\n\t<\/div>\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-1126532804\">\n\n\n\t<div id=\"col-1506737044\" class=\"col medium-10 small-12 large-8\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-747149137\" class=\"text\">\n\t\t\n\n<h2><strong>Disciplinas UBIS<\/strong><\/h2>\n\t\t\n<style>\n#text-747149137 {\n  font-size: 1.5rem;\n  text-align: center;\n  color: #086037;\n}\n#text-747149137 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:6000px;height:2px;\"><\/div>\n\n\t<div id=\"text-2756930265\" class=\"text\">\n\t\t\n\n<p>La disciplina de Ventas y Marketing garantiza que UBIS conecta sus productos con los clientes de forma eficaz, impulsa el crecimiento de los ingresos y refuerza la marca en todos los mercados.<\/p>\n<p>Abarca varias \u00e1reas clave:<\/p>\n\t\t\n<style>\n#text-2756930265 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1506737044 > .col-inner {\n  margin: 0px 0px -30px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row align-center\"  id=\"row-981742328\">\n\n\n\t<div id=\"col-969738540\" class=\"col medium-3 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-454462751\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-454462751 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/International-Sales.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-1408435718\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><strong>Ventas internacionales<\/strong><\/h4>\n\t\t\n<style>\n#text-1408435718 {\n  text-align: center;\n  color: #086037;\n}\n#text-1408435718 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1256212388\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1256212388 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p class=\"p1\">Impulsar la expansi\u00f3n global de UBIS, gestionando las cuentas clave,<br \/>\ny cultivar asociaciones en el extranjero.<\/p>\n\t<div id=\"gap-626644663\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-626644663 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-969738540 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1205491188\" class=\"col medium-3 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-529636083\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-529636083 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Domestic-Sales.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-2106183089\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><strong>Ventas nacionales<\/strong><\/h4>\n\t\t\n<style>\n#text-2106183089 {\n  text-align: center;\n  color: #086037;\n}\n#text-2106183089 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-826037435\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-826037435 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p class=\"p1\">Impulsar el crecimiento de las ventas en los mercados locales, comprender las necesidades de los clientes y garantizar altos niveles de servicio.<\/p>\n\t<div id=\"gap-1423940755\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1423940755 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1205491188 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1631786542\" class=\"col medium-3 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1503120902\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1503120902 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Marketing-Coordination.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-992640719\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><strong>Coordinaci\u00f3n de marketing<\/strong><\/h4>\n\t\t\n<style>\n#text-992640719 {\n  text-align: center;\n  color: #086037;\n}\n#text-992640719 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-54810440\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-54810440 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p>Apoyo a la planificaci\u00f3n de campa\u00f1as, lanzamientos de productos y colaboraci\u00f3n interfuncional para maximizar el impacto en el mercado.<\/p>\n\t<div id=\"gap-815674666\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-815674666 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1631786542 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-1891620989\" class=\"col medium-3 small-12 large-3\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-center\" style=\"background-color:rgba(59, 172, 119, 0.099);\" >\n\t\t\t\n\t\t\t\n\n\t<div id=\"gap-1605627870\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1605627870 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<div class=\"icon-box featured-box icon-box-top text-left\"  >\n\t\t\t\t\t<div class=\"icon-box-img\" style=\"width: 106px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" >\n\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-300x300.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-300x300.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-1024x1024.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-150x150.png 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-768x768.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-247x247.png 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-510x510.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding-100x100.png 100w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/Media-Marketing-Branding.png 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\n\t<div id=\"text-1854719681\" class=\"text\">\n\t\t\n\n<h4 class=\"p1\"><strong>Medios de comunicaci\u00f3n, marketing y marca<\/strong><\/h4>\n\t\t\n<style>\n#text-1854719681 {\n  text-align: center;\n  color: #086037;\n}\n#text-1854719681 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"gap-1296595645\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1296595645 {\n  padding-top: 10px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n<p class=\"p1\">Desarrollo de estrategias de marca, gesti\u00f3n de campa\u00f1as en medios digitales y tradicionales y mejora de la presencia de la UBIS en el mercado.<\/p>\n\t<div id=\"gap-384997268\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-384997268 {\n  padding-top: 20px;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1891620989 > .col-inner {\n  padding: 0px 10px 0px 10px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1288678090 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n@media (min-width:550px) {\n  #section_1288678090 {\n    padding-top: 30px;\n    padding-bottom: 30px;\n  }\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\t<section class=\"section\" id=\"section_1966919154\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t<img decoding=\"async\" width=\"2048\" height=\"1536\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/07\/S__33406994-scaled.jpg\" class=\"bg attachment-original size-original\" alt=\"\" \/>\t\t\t\t\t\t<div class=\"section-bg-overlay absolute fill\"><\/div>\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\n  <div class=\"banner has-hover\" id=\"banner-1372004277\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1024x576.webp\" class=\"bg attachment-large size-large\" alt=\"\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n   <div id=\"text-box-253498608\" class=\"text-box banner-layer x85 md-x95 lg-x95 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div id=\"text-2536682011\" class=\"text\">\n\t\t\n\n<h2 class=\"uppercase\"><strong>\u00daNETE A NUESTRA COMUNIDAD<\/strong><\/h2>\n\t\t\n<style>\n#text-2536682011 {\n  text-align: center;\n  color: #086037;\n}\n#text-2536682011 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1086250723\" class=\"text\">\n\t\t\n\n<h5>Su pr\u00f3xima gran oportunidad est\u00e1 a un solo clic<\/h5>\n\t\t\n<style>\n#text-1086250723 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<a data-animate=\"fadeInLeft\" href=\"https:\/\/forms.cloud.microsoft\/pages\/responsepage.aspx?id=wfacPzJGYkuvbyn0aNXToPsbEW4aN3pDsQP3qJmcr7JUNjQ5OU9XWUU1VFBKUTBWSVoyVElQN0RYVi4u&#038;route=shorturl\" target=\"_blank\" class=\"button primary\" rel=\"noopener\">\n\t\t<span>WORK WITH US<\/span>\n\t<\/a>\n\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-253498608 {\n  width: 68%;\n}\n#text-box-253498608 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-253498608 {\n    width: 44%;\n  }\n}\n<\/style>\n    <\/div>\n \n   <div id=\"text-box-201161222\" class=\"text-box banner-layer x5 md-x5 lg-x5 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\n\t<div class=\"img has-hover hide-for-small x md-x lg-x y md-y lg-y\" id=\"image_802636358\">\n\t\t\t\t\t\t\t\t<div class=\"img-inner image-fade-in dark\" >\n\t\t\t<img decoding=\"async\" width=\"1020\" height=\"574\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1024x576.webp\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1024x576.webp 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-300x169.webp 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-768x432.webp 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-1536x864.webp 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-scaled.webp 2048w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/11\/IMG_7426-2-510x287.webp 510w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\n<style>\n#image_802636358 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-201161222 {\n  width: 41%;\n}\n#text-box-201161222 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1372004277 {\n  padding-top: 300px;\n  background-color: rgb(255, 255, 255);\n}\n#banner-1372004277 .overlay {\n  background-color: rgba(246, 246, 246, 0.901);\n}\n@media (min-width:550px) {\n  #banner-1372004277 {\n    padding-top: 400px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1966919154 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n}\n#section_1966919154 .section-bg-overlay {\n  background-color: rgba(2, 104, 56, 0.878);\n}\n<\/style>\n\t<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1340,"parent":44,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-8060","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/8060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/comments?post=8060"}],"version-history":[{"count":10,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/8060\/revisions"}],"predecessor-version":[{"id":8788,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/8060\/revisions\/8788"}],"up":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/44"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media\/1340"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media?parent=8060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}