{"id":36,"date":"2025-06-23T15:48:10","date_gmt":"2025-06-23T08:48:10","guid":{"rendered":"https:\/\/ubisasia.com\/?page_id=36"},"modified":"2026-01-16T10:35:29","modified_gmt":"2026-01-16T03:35:29","slug":"products","status":"publish","type":"page","link":"https:\/\/www.ubisasia.com\/es\/products\/","title":{"rendered":"Productos"},"content":{"rendered":"<section class=\"section\" id=\"section_182448294\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-center\"  id=\"row-1302095518\">\n\n\n\t<div id=\"col-1386888113\" class=\"col medium-10 small-12 large-10\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3928203872\" class=\"text\">\n\t\t\n\n<h1><strong>Productos UBIS<\/strong><\/h1>\n\t\t\n<style>\n#text-3928203872 {\n  font-size: 2rem;\n  text-align: center;\n  color: #086037;\n}\n#text-3928203872 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2806069217\" class=\"text\">\n\t\t\n\n<p><strong>UBIS Asia Public Company Limited<\/strong> se dedica a suministrar al sector del envasado soluciones qu\u00edmicas de alto rendimiento formuladas cient\u00edficamente. Nuestra gama de productos abarca materiales avanzados fundamentales para mantener la integridad y el rendimiento de los envases en diversos sustratos. Para los envases met\u00e1licos, ofrecemos sellantes compuestos dise\u00f1ados con propiedades de fluidez \u00f3ptimas y una adhesi\u00f3n superior para garantizar el sellado herm\u00e9tico y la resistencia a la corrosi\u00f3n. Nuestras lacas de recubrimiento especializadas ofrecen una s\u00f3lida barrera de protecci\u00f3n contra la interacci\u00f3n del producto y los elementos externos. Adem\u00e1s, nuestra divisi\u00f3n de envases flexibles suministra tintas de huecograbado y flexogr\u00e1ficas de \u00faltima generaci\u00f3n desarrolladas para una fidelidad crom\u00e1tica y una imprimibilidad estable, con el apoyo de adhesivos y recubrimientos especializados que mejoran la fuerza de uni\u00f3n de la laminaci\u00f3n, las propiedades de barrera y las caracter\u00edsticas de termosellado, cumpliendo las estrictas normas industriales y reglamentarias.<\/p>\n\t\t\n<style>\n#text-2806069217 {\n  text-align: center;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"text-center\"><div class=\"is-divider divider clearfix\" style=\"max-width:2000px;height:2px;\"><\/div><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_182448294 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n  background-color: rgb(244, 244, 244);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_1016585795\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-963442818\">\n\n\n\t<div id=\"col-1004078254\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_1794101197\">\n\t\t\t\t\t\t<div data-animate=\"fadeInDown\">\t\t<div class=\"img-inner image-cover dark\" style=\"padding-top:76%;\">\n\t\t\t<img decoding=\"async\" width=\"940\" height=\"788\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/08\/can-can-png.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/08\/can-can-png.png 940w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/08\/can-can-png-300x251.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/08\/can-can-png-768x644.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/08\/can-can-png-510x428.png 510w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_1794101197 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1004078254 > .col-inner {\n  margin: 0px 0px -37px 0px;\n}\n@media (min-width:550px) {\n  #col-1004078254 > .col-inner {\n    margin: 0px 0px -79px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-981791192\" class=\"col medium-5 small-11 large-5\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3105598733\" class=\"text\">\n\t\t\n\n<h5>Soluciones para<\/h5>\n<h2><strong>Envases met\u00e1licos<br><\/strong><\/h2>\n\t\t\n<style>\n#text-3105598733 {\n  font-size: 1.7rem;\n  text-align: right;\n  color: #086037;\n}\n#text-3105598733 > * {\n  color: #086037;\n}\n@media (min-width:550px) {\n  #text-3105598733 {\n    font-size: 1.5rem;\n    text-align: right;\n  }\n}\n@media (min-width:850px) {\n  #text-3105598733 {\n    text-align: right;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3935689113\" class=\"text\">\n\t\t\n\n<p>Compuestos Selladores, Recubrimientos Lacas<\/p>\n\t\t\n<style>\n#text-3935689113 {\n  font-size: 1.2rem;\n  text-align: right;\n  color: #0f0f0f;\n}\n#text-3935689113 > * {\n  color: #0f0f0f;\n}\n@media (min-width:850px) {\n  #text-3935689113 {\n    text-align: right;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/es\/metal-packaging\/\" class=\"button primary is-outline lowercase\"  >\n\t\t<span>M\u00e1s informaci\u00f3n<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1016585795 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 500px;\n  background-color: rgb(244, 244, 244);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section dark\" id=\"section_1479386191\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row align-middle align-center\"  id=\"row-24284300\">\n\n\n\t<div id=\"col-595257587\" class=\"col medium-5 small-11 large-5\"  data-animate=\"fadeInUp\">\n\t\t\t\t<div class=\"col-inner text-left\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-2062563752\" class=\"text\">\n\t\t\n\n<h5>Soluciones para<\/h5>\n<h2><strong>Envases no met\u00e1licos<\/strong><\/h2>\n\t\t\n<style>\n#text-2062563752 {\n  font-size: 1.7rem;\n  text-align: left;\n  color: #086037;\n}\n#text-2062563752 > * {\n  color: #086037;\n}\n@media (min-width:550px) {\n  #text-2062563752 {\n    font-size: 1.5rem;\n  }\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-2736317616\" class=\"text\">\n\t\t\n\n<p>Tintas, adhesivos, revestimientos<\/p>\n\t\t\n<style>\n#text-2736317616 {\n  font-size: 1.2rem;\n  color: #0f0f0f;\n}\n#text-2736317616 > * {\n  color: #0f0f0f;\n}\n<\/style>\n\t<\/div>\n\t\n<a href=\"\/es\/non-metal-packaging\/\" class=\"button primary is-outline lowercase\"  >\n\t\t<span>M\u00e1s informaci\u00f3n<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1231275107\" class=\"col medium-5 small-12 large-5 small-col-first\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div class=\"img has-hover x md-x lg-x y md-y lg-y\" id=\"image_896960915\">\n\t\t\t\t\t\t<div data-animate=\"fadeInDown\">\t\t<div class=\"img-inner dark\" >\n\t\t\t<img decoding=\"async\" width=\"660\" height=\"515\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Copy-of-Copy-of-UBIS-Gravure-Ink-Catalogue-1.pdf-9-1-e1752382694591.png\" class=\"attachment-original size-original\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Copy-of-Copy-of-UBIS-Gravure-Ink-Catalogue-1.pdf-9-1-e1752382694591.png 660w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Copy-of-Copy-of-UBIS-Gravure-Ink-Catalogue-1.pdf-9-1-e1752382694591-510x398.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Copy-of-Copy-of-UBIS-Gravure-Ink-Catalogue-1.pdf-9-1-e1752382694591-300x234.png 300w\" sizes=\"(max-width: 660px) 100vw, 660px\" \/>\t\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t<\/div>\t\t\t\t\t\t\n<style>\n#image_896960915 {\n  width: 100%;\n}\n<\/style>\n\t<\/div>\n\t\n\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1231275107 > .col-inner {\n  margin: 0px 0px -25px 0px;\n}\n@media (min-width:550px) {\n  #col-1231275107 > .col-inner {\n    margin: 0px 0px -79px 0px;\n  }\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1479386191 {\n  padding-top: 0px;\n  padding-bottom: 0px;\n  min-height: 500px;\n  background-color: rgb(244, 244, 244);\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1940355048\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n<div class=\"row\"  id=\"row-933346204\">\n\n\n\t<div id=\"col-1497720546\" class=\"col small-12 large-12\"  data-animate=\"fadeInDown\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\t<div id=\"text-3956908562\" class=\"text\">\n\t\t\n\n<h1><strong>\u00daltimos blogs<\/strong><\/h1>\n\t\t\n<style>\n#text-3956908562 {\n  font-size: 1.3rem;\n  text-align: center;\n  color: #086037;\n}\n#text-3956908562 > * {\n  color: #086037;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:6000px;height:2px;\"><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n<div class=\"row\"  id=\"row-1279032698\">\n\n\n\t<div id=\"col-1080608482\" class=\"col small-12 large-12\"  data-animate=\"bounceInLeft\">\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n  \n    <div class=\"row large-columns-3 medium-columns-3 small-columns-1 slider row-slider slider-nav-circle slider-nav-outside slider-nav-push\"  data-flickity-options='{&quot;imagesLoaded&quot;: true, &quot;groupCells&quot;: &quot;100%&quot;, &quot;dragThreshold&quot; : 5, &quot;cellAlign&quot;: &quot;left&quot;,&quot;wrapAround&quot;: true,&quot;prevNextButtons&quot;: true,&quot;percentPosition&quot;: true,&quot;pageDots&quot;: false, &quot;rightToLeft&quot;: false, &quot;autoPlay&quot; : 3000}' >\n\n  <div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/5-reasons-compound-sealants-hero-metal-packaging\/\" class=\"plain\" aria-label=\"5 Reasons Why Compound Sealants are the Silent Heroes of Metal Packaging\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"875\" height=\"569\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Ratio-65-for-blog-post-6.png\" class=\"attachment-original size-original wp-post-image\" alt=\"Why Compound Sealants are the Silent Heroes of Metal Packaging\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Ratio-65-for-blog-post-6.png 875w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Ratio-65-for-blog-post-6-300x195.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Ratio-65-for-blog-post-6-768x499.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Ratio-65-for-blog-post-6-18x12.png 18w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2026\/03\/Ratio-65-for-blog-post-6-510x332.png 510w\" sizes=\"(max-width: 875px) 100vw, 875px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/5-reasons-compound-sealants-hero-metal-packaging\/\" class=\"plain\">5 Reasons Why Compound Sealants are the Silent Heroes of Metal Packaging<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t5 Reasons Why Compound Sealants are the Silent Heroes of Metal Packaging\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/gravure-ink-printing-packaging\/\" class=\"plain\" aria-label=\"Tinta de huecograbado (\u0e2a\u0e35\u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e01\u0e23\u0e32\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c) \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"455\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Ratio-65-for-blog-post-2.png\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Ratio-65-for-blog-post-2.png 700w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Ratio-65-for-blog-post-2-300x195.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/10\/Ratio-65-for-blog-post-2-510x332.png 510w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/gravure-ink-printing-packaging\/\" class=\"plain\">Tinta de huecograbado (\u0e2a\u0e35\u0e2b\u0e21\u0e36\u0e01\u0e1e\u0e34\u0e21\u0e1e\u0e4c\u0e01\u0e23\u0e32\u0e40\u0e27\u0e35\u0e22\u0e23\u0e4c) \u0e2b\u0e31\u0e27\u0e43\u0e08\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e1a\u0e23\u0e23\u0e08\u0e38\u0e20\u0e31\u0e13\u0e11\u0e4c\u0e22\u0e38\u0e04\u0e43\u0e2b\u0e21\u0e48\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e34\u0e21\u0e1e\u0e4c<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/pvc-plastisol\/\" class=\"plain\" aria-label=\"PVC Plastisol\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/08\/pvc-plastisol.png\" class=\"attachment-original size-original wp-post-image\" alt=\"pvc plastisol UBIS\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/08\/pvc-plastisol.png 800w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/08\/pvc-plastisol-300x225.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/08\/pvc-plastisol-768x576.png 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/08\/pvc-plastisol-510x383.png 510w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/pvc-plastisol\/\" class=\"plain\">PVC Plastisol<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/why-are-cans-coated\/\" class=\"plain\" aria-label=\"\u00bfPor qu\u00e9 se recubren las latas?\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"536\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Why-are-cans-coated-1-1024x536-1.png\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Why-are-cans-coated-1-1024x536-1.png 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Why-are-cans-coated-1-1024x536-1-510x267.png 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Why-are-cans-coated-1-1024x536-1-300x157.png 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Why-are-cans-coated-1-1024x536-1-768x402.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/why-are-cans-coated\/\" class=\"plain\">\u00bfPor qu\u00e9 se recubren las latas?<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\tEl alimento que contienen las latas es la raz\u00f3n principal por la que las recubrimos. El recubrimiento\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/5-key-benefits-of-external-lacquer-for-canned-food\/\" class=\"plain\" aria-label=\"5 principales ventajas de la laca externa para conservas\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1200\" height=\"900\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/11\/ezgif-28202729631a46.webp\" class=\"attachment-original size-original wp-post-image\" alt=\"5 Key Benefits of External Lacquer for Canned Food\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/11\/ezgif-28202729631a46.webp 1200w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/11\/ezgif-28202729631a46-300x225.webp 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/11\/ezgif-28202729631a46-1024x768.webp 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/11\/ezgif-28202729631a46-768x576.webp 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/11\/ezgif-28202729631a46-510x383.webp 510w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/5-key-benefits-of-external-lacquer-for-canned-food\/\" class=\"plain\">5 principales ventajas de la laca externa para conservas<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b9%83%e0%b8%94%e0%b9%80%e0%b8%a3%e0%b8%b2%e0%b8%96%e0%b8%b6%e0%b8%87%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%8a%e0%b9%89-sealing-compounds\/\" class=\"plain\" aria-label=\"\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14\u0e40\u0e23\u0e32\u0e16\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49 Compuestos de sellado \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23-05-07-2024-900x600-1.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23-05-07-2024-900x600-1.jpg 900w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23-05-07-2024-900x600-1-510x340.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23-05-07-2024-900x600-1-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/06\/Sealing-Compounds-\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23-05-07-2024-900x600-1-768x512.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/%e0%b9%80%e0%b8%ab%e0%b8%95%e0%b8%b8%e0%b9%83%e0%b8%94%e0%b9%80%e0%b8%a3%e0%b8%b2%e0%b8%96%e0%b8%b6%e0%b8%87%e0%b8%95%e0%b9%89%e0%b8%ad%e0%b8%87%e0%b9%83%e0%b8%8a%e0%b9%89-sealing-compounds\/\" class=\"plain\">\u0e40\u0e2b\u0e15\u0e38\u0e43\u0e14\u0e40\u0e23\u0e32\u0e16\u0e36\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49 Compuestos de sellado \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e22\u0e32\u0e41\u0e19\u0e27\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e37\u0e48\u0e21<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/get-to-know-sealing-compound-in-food-packaging\/\" class=\"plain\" aria-label=\"Conozca el compuesto sellante: El coraz\u00f3n de la seguridad y la frescura en el envasado de alimentos\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"526\" height=\"526\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01.jpg 526w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01-300x300.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01-150x150.jpg 150w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01-247x247.jpg 247w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01-510x510.jpg 510w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2025\/09\/Sealing-Compounds-\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01-100x100.jpg 100w\" sizes=\"(max-width: 526px) 100vw, 526px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/get-to-know-sealing-compound-in-food-packaging\/\" class=\"plain\">Conozca el compuesto sellante: El coraz\u00f3n de la seguridad y la frescura en el envasado de alimentos<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49 Compuestos de sellado \u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e34\u0e14\u0e01\u0e23\u0e30\u0e1b\u0e4b\u0e2d\u0e07\u0e42\u0e25\u0e2b\u0e30\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e19\u0e31\u0e49\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e48\u0e07\u0e1c\u0e25\u0e15\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e02\u0e2d\u0e07\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e07\u0e40\u0e2d\u0e32\u0e43\u0e08\u0e43\u0e2a\u0e48\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04\u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e1c\u0e31\u0e2a\u0e01\u0e31\u0e1a\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e42\u0e14\u0e22\u0e15\u0e23\u0e07 \u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e2a\u0e21\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e25\u0e31\u0e01 \u0e46 \u0e02\u0e2d\u0e07 Compuestos sellantes \u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 1. \u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e48\u0e27\u0e0b\u0e36\u0e21 \u0e0a\u0e48\u0e27\u0e22\u0e43\u0e2b\u0e49\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e04\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e14\u0e43\u0e2b\u0e21\u0e48 \u0e41\u0e25\u0e30\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22\u0e15\u0e25\u0e2d\u0e14\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><div class=\"col post-item\" >\n\t\t\t<div class=\"col-inner\">\n\t\t\t\t<div class=\"box box-normal box-text-bottom box-blog-post has-hover\">\n            \t\t\t\t\t<div class=\"box-image\" >\n  \t\t\t\t\t\t<div class=\"image-cover\" style=\"padding-top:65%;\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/compound-appication-for-cans\/\" class=\"plain\" aria-label=\"Compuesto Aplicaci\u00f3n para latas\">\n\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024.jpg\" class=\"attachment-original size-original wp-post-image\" alt=\"Sealing Compounds\" srcset=\"https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024.jpg 1920w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024-300x200.jpg 300w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024-1024x683.jpg 1024w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024-768x512.jpg 768w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024-1536x1024.jpg 1536w, https:\/\/www.ubisasia.com\/wp-content\/uploads\/2024\/10\/Sealing-Compounds-04-07-2024-510x340.jpg 510w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t<\/a>\n  \t\t\t\t\t\t\t  \t\t\t\t\t\t\t  \t\t\t\t\t\t<\/div>\n  \t\t\t\t\t\t  \t\t\t\t\t<\/div>\n          \t\t\t\t\t<div class=\"box-text text-left\" >\n\t\t\t\t\t<div class=\"box-text-inner blog-post-inner\">\n\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h5 class=\"post-title is-large\">\n\t\t\t\t\t\t<a href=\"https:\/\/www.ubisasia.com\/es\/compound-appication-for-cans\/\" class=\"plain\">Compuesto Aplicaci\u00f3n para latas<\/a>\n\t\t\t\t\t<\/h5>\n\t\t\t\t\t\t\t\t\t\t<div class=\"is-divider\"><\/div>\n\t\t\t\t\t\t\t\t\t\t<p class=\"from_the_blog_excerpt\">\n\t\t\t\t\t\t\t\t\t\t\t<\/p>\n\t\t\t\t\t                    \n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div><\/div>\n\n<div class=\"row\"  id=\"row-1398117735\">\n\n\n\t<div id=\"col-1146004173\" class=\"col medium-7 small-12 large-7\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-870520277\" class=\"col medium-5 small-12 large-5\"  >\n\t\t\t\t<div class=\"col-inner text-right\"  >\n\t\t\t\n\t\t\t\n\n<a href=\"\/es\/articles\/\" class=\"button primary is-underline lowercase\"  >\n\t\t<span>Descubra m\u00e1s art\u00edculos<\/span>\n\t<i class=\"icon-angle-right\" aria-hidden=\"true\" ><\/i><\/a>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1080608482 > .col-inner {\n  padding: 0px 15px 0px 15px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1940355048 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":930,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-36","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/36","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/comments?post=36"}],"version-history":[{"count":9,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/36\/revisions"}],"predecessor-version":[{"id":8379,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/pages\/36\/revisions\/8379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media\/930"}],"wp:attachment":[{"href":"https:\/\/www.ubisasia.com\/es\/wp-json\/wp\/v2\/media?parent=36"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}